{"id":1428,"date":"2022-01-27T14:04:43","date_gmt":"2022-01-27T14:04:43","guid":{"rendered":"https:\/\/test.campinghuertaromero.es\/?page_id=1428"},"modified":"2022-01-27T14:04:43","modified_gmt":"2022-01-27T14:04:43","slug":"privacy-and-cookies-policy","status":"publish","type":"page","link":"https:\/\/campinghuertaromero.es\/en\/politicas-de-privacidad-y-cookies\/","title":{"rendered":"Privacy and Cookie Policies"},"content":{"rendered":"\n<p><strong>1.- AVISO LEGAL<\/strong><\/p>\n\n\n\n<p><strong>2.- POLITICA DE PRIVACIDAD<\/strong><\/p>\n\n\n\n<p><strong>3.- POLITICA DE COOKIES<\/strong><\/p>\n\n\n\n<p><strong>4.- FALDON COOKIES<\/strong><\/p>\n\n\n\n<p><strong>5.- BASES ESTANDAR CONCURSOS<\/strong><\/p>\n\n\n\n<p><strong>6.- TEXTO AUTORIZACION CONTACTO<\/strong><\/p>\n\n\n\n<p><strong>7.- FORMATO AUTORIZACION NEWSLETTER<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"aviso-legal\"><strong>AVISO LEGAL<\/strong><strong>&nbsp;<\/strong><\/h2>\n\n\n\n<p><strong>AVISO LEGAL:<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;<\/strong>En cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSICE) a continuaci\u00f3n se detallan los datos identificativos de la empresa:<\/p>\n\n\n\n<p>Nombre empresa:<\/p>\n\n\n\n<p>Raz\u00f3n social: MIGUEL GONZ\u00c1LEZ MICHAELIS,(<strong>En adelante, CAMPING HUERTA ROMERO<\/strong>).&nbsp;<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>NIF: 51095018-N.<\/p>\n\n\n\n<p>Direcci\u00f3n: PASEO MARITIMO, 18, 18740, CASTELL DE FERRO, GRANADA.<\/p>\n\n\n\n<p>Tel\u00e9fono: 958 65 60 01<\/p>\n\n\n\n<p>Email:&nbsp;<a href=\"mailto:campinghuertaromero@gmail.com\">campinghuertaromero@gmail.com<\/a><\/p>\n\n\n\n<p><strong>FINALIDAD DE LA P\u00c1GINA WEB.<\/strong><\/p>\n\n\n\n<p>Venta de servicios y\/o productos relacionados con&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>. El presente aviso legal (en adelante, el \u00abAviso Legal\u00bb) regula el uso del sitio web:&nbsp;<a href=\"https:\/\/www.campinghuertaromero.es\/\">www.campinghuertaromero.es<\/a><\/p>\n\n\n\n<p><strong>LEGISLACI\u00d3N.<\/strong><\/p>\n\n\n\n<p>Con car\u00e1cter general las relaciones entre&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>(51095018-N) con los Usuarios de sus servicios telem\u00e1ticos, presentes en este sitio web, se encuentran sometidas a la legislaci\u00f3n y jurisdicci\u00f3n espa\u00f1olas.<\/p>\n\n\n\n<p><strong>USO Y ACCESO DE USUARIOS.<\/strong><\/p>\n\n\n\n<p>El Usuario queda informado, y acepta, que el acceso a la presente web no supone, en modo alguno, el inicio de una relaci\u00f3n comercial con&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>o cualquiera de sus delegaciones.<\/p>\n\n\n\n<p><strong>PROPIEDAD INTELECTUAL E INDUSTRIAL.<\/strong><\/p>\n\n\n\n<p>Los derechos de propiedad intelectual del contenido de las p\u00e1ginas web, su dise\u00f1o gr\u00e1fico y c\u00f3digos son titularidad de&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>y, por tanto, queda prohibida su reproducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica, transformaci\u00f3n o cualquier otra actividad que se pueda realizar con los contenidos de sus p\u00e1ginas web ni aun citando las fuentes, salvo consentimiento por escrito de&nbsp;<strong>CAMPING HUERTA ROMERO.<\/strong>&nbsp;&nbsp;<strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>CONTENIDO DE LA WEB Y ENLACES (LINKS).<\/strong><\/p>\n\n\n\n<p><strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>se reserva el derecho a actualizar, modificar o eliminar la informaci\u00f3n contenida en sus p\u00e1ginas web pudiendo incluso limitar o no permitir el acceso a dicha informaci\u00f3n a ciertos usuarios.<\/p>\n\n\n\n<p><strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>no asume responsabilidad alguna por la informaci\u00f3n contenida en p\u00e1ginas web de terceros a las que se pueda acceder por \u00ablinks\u00bb o enlaces desde cualquier p\u00e1gina web propiedad de&nbsp;<strong>CAMPING HUERTA ROMERO.<\/strong>&nbsp;<strong>&nbsp;<\/strong>&nbsp;<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>La presencia de \u00ablinks\u00bb o enlaces en las p\u00e1ginas web de&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>tiene finalidad meramente informativa y en ning\u00fan caso supone sugerencia, invitaci\u00f3n o recomendaci\u00f3n sobre los mismos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"politica-de-privacidad\"><strong>POLITICA DE PRIVACIDAD<\/strong><\/h2>\n\n\n\n<p><strong>POL\u00cdTICA DE PRIVACIDAD:<\/strong><\/p>\n\n\n\n<p>En esta&nbsp;<strong>Pol\u00edtica de Privacidad&nbsp;<\/strong>encontrar\u00e1 toda la informaci\u00f3n sobre la apliaci\u00f3n de los datos personales de nuestros clientes y usuarios, con independencia del canal o medio (online o en persona) de&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>, que utilice para interactuar con nosotros.<\/p>\n\n\n\n<p>Como principio de transparencia, desde&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>&nbsp;te indicamos las implicaciones y usos que llevamos a cabo, as\u00ed como los derechos de los que dispones.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ponemos a tu disposici\u00f3n de forma&nbsp;<strong>permanente toda la informaci\u00f3n&nbsp;<\/strong>en esta Pol\u00edtica de Privacidad que puedes consultar cuando lo estimes oportuno y adem\u00e1s podr\u00e1s tener informaci\u00f3n acerca del tratamiento de tus datos, conforme vayas interactuando con nosotros.<\/li><li>Cuando hablamos de nuestra plataforma web, nos referimos en general a cualquiera de los canales o medios digitales o f\u00edsicos con los que puedas interactuar con nosotros.<\/li><li>Nuestra web,&nbsp;<a href=\"https:\/\/www.campinghuertaromero.es\/\">campinghuertaromero.es<\/a><\/li><li>Nuestras tiendas, v\u00e9ase anexo I, a la presente pol\u00edtica de privacidad.<\/li><\/ul>\n\n\n\n<ol class=\"wp-block-list\"><li>\u00bfQUI\u00c9N ES EL RESPONSABLE DEL TRATAMIENTO DE TUS DATOS?<\/li><\/ol>\n\n\n\n<p>El responsable del tratamiento de tus datos es:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Nombre empresa: CAMPING HUERTA ROMERO<\/li><li>Raz\u00f3n social: MIGUEL GONZ\u00c1LEZ MICHAELIS,(<strong>En adelante, CAMPING HUERTA ROMERO<\/strong>).<\/li><li>NIF: 51095018-N.<\/li><li>Direcci\u00f3n: PASEO MARITIMO, 18, 18740, CASTELL DE FERRO, GRANADA.<\/li><li>Tel\u00e9fono: 958 65 60 01.<\/li><li>Email:&nbsp;<a href=\"mailto:campinghuertaromero@gmail.com\">campinghuertaromero@gmail.com<\/a><\/li><\/ul>\n\n\n\n<p>EXACTITUD Y VERACIDAD DE LOS DATOS FACILITADOS<\/p>\n\n\n\n<p>El Usuario que env\u00eda la informaci\u00f3n a&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>&nbsp;es el \u00fanico responsable de la veracidad y correcci\u00f3n de los datos incluidos, exoner\u00e1ndose&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>&nbsp;de cualquier responsabilidad al respecto.<\/p>\n\n\n\n<p>Los usuarios garantizan y responden, en cualquier caso, de la exactitud, vigencia y autenticidad de los datos personales facilitados, y se comprometen a mantenerlos debidamente actualizados.<\/p>\n\n\n\n<p>El usuario acepta proporcionar informaci\u00f3n completa y correcta en el formulario de registro o suscripci\u00f3n.<\/p>\n\n\n\n<p><strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>no responde de la veracidad de las informaciones que no sean de elaboraci\u00f3n propia y de las que se indique otra fuente, por lo que tampoco asume responsabilidad alguna en cuanto a hipot\u00e9ticos perjuicios que pudieran originarse por el uso de dicha informaci\u00f3n. Se exonera a&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>&nbsp;de responsabilidad ante cualquier da\u00f1o o perjuicio que pudiera sufrir el Usuario como consecuencia de errores, defectos u omisiones, en la informaci\u00f3n siempre que proceda de fuentes ajenas a&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>\u00bfCON QU\u00c9 FINALIDAD TRATAMOS TUS DATOS PERSONALES?<\/li><\/ol>\n\n\n\n<p>Dependiendo de los productos, servicios o funcionalidades de los que quieras disfrutar en cada momento necesitaremos tratar unos datos u otros, que en general ser\u00e1n, seg\u00fan el caso, los siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>tus&nbsp;<strong>datos identificativos&nbsp;<\/strong>(por ejemplo, tu nombre, apellido, idioma y pa\u00eds desde el que interact\u00faas con nosotros, datos de contacto, etc);<\/li><li>informaci\u00f3n&nbsp;<strong>econ\u00f3mica y transaccional&nbsp;<\/strong>(por ejemplo, tus datos de pago o de tarjeta, informaci\u00f3n acerca de tus compras, pedidos, devoluciones, );<\/li><li>datos de&nbsp;<strong>conexi\u00f3n, geolocalizaci\u00f3n y navegaci\u00f3n&nbsp;<\/strong>(en caso de que interact\u00faes con nosotros desde el m\u00f3vil, por ejemplo);<\/li><li>informaci\u00f3n&nbsp;<strong>comercial&nbsp;<\/strong>(por ejemplo, si est\u00e1s suscrito a nuestra newsletter),<\/li><li>datos sobre tus&nbsp;<strong>gustos y preferencias<\/strong>.<\/li><\/ul>\n\n\n\n<p>Recuerda que, cuando te pidamos que rellenes tus datos personales para darte acceso a alguna funcionalidad o servicio de la Plataforma, marcaremos algunos campos como&nbsp;<em>obligatorios<\/em>, puesto que son datos que necesitamos para poder prestarte el servicio o darte acceso a la funcionalidad en cuesti\u00f3n. Por favor, ten en cuenta que si decides no facilitarnos esos datos, es posible que no puedas completar tu registro como usuario o que no puedas disfrutar de esos servicios o funcionalidades.<\/p>\n\n\n\n<p>Dependiendo de c\u00f3mo interact\u00faes con nuestra Plataforma, trataremos tus datos personales para las siguientes finalidades:<\/p>\n\n\n\n<p>Dependiendo de los productos, servicios o funcionalidades de los que quieras disfrutar en cada momento necesitaremos tratar unos datos u otros, que en general ser\u00e1n, seg\u00fan las siguientes finalidades:<\/p>\n\n\n\n<p><strong>1.- &nbsp;<\/strong>Para gestionar&nbsp;<strong>tu registro como usuario de nuestra web.<\/strong><\/p>\n\n\n\n<p><strong>2.-&nbsp;<\/strong>Para el&nbsp;<strong>desarrollo, cumplimiento y ejecuci\u00f3n del contrato de compraventa o de servicios&nbsp;<\/strong>que hayas contratado con nosotros en nuestra web.<\/p>\n\n\n\n<p><strong>3.-&nbsp;<\/strong>Para atender las solicitudes o peticiones que realices a trav\u00e9s de los canales de&nbsp;<strong>Atenci\u00f3n al Cliente.<\/strong><\/p>\n\n\n\n<p><strong>4.-&nbsp;<\/strong>Para fines de&nbsp;<strong>marketing.<\/strong><\/p>\n\n\n\n<p><strong>5.- An\u00e1lisis de usabilidad y de calidad&nbsp;<\/strong>para la mejora de nuestros servicios.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\"><li>\u00bfCU\u00c1L ES LA LEGITIMACI\u00d3N PARA EL TRATAMIENTO DE TUS DATOS?<\/li><\/ol>\n\n\n\n<p>La base legal que nos permite tratar tus datos personales tambi\u00e9n depende de la finalidad para la que los tratemos, seg\u00fan lo explicado en la siguiente tabla:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>FINALIDAD<\/td><td>LEGITIMACION<\/td><\/tr><tr><td><strong>1. Gestionar tu registro como usuario de la WEB<\/strong><\/td><td>El tratamiento de tus datos es&nbsp;<strong>necesario para la&nbsp; ejecuci\u00f3n de los t\u00e9rminos que regulan el uso de la web<\/strong>. En otras palabras, para que puedas registrarte como usuario en la web, necesitamos tratar tus datos personales, ya que de lo contrario no podr\u00edamos gestionar tu registro.En el caso de que elijas utilizar el acceso o inicio de sesi\u00f3n a trav\u00e9s una red social, el motivo por el que estamos legitimados para tratar tus datos es el&nbsp;<strong>consentimiento&nbsp;<\/strong>que prestas en el momento de autorizar la cesi\u00f3n de tus datos desde la red social.<\/td><\/tr><tr><td><strong>2. Desarrollo, cumplimiento y ejecuci\u00f3n del contrato de compraventa o de servicios<\/strong><\/td><td>El tratamiento de tus datos es necesario para la&nbsp;<strong>ejecuci\u00f3n del contrato de compraventa&nbsp;<\/strong>o de&nbsp;<strong>prestaci\u00f3n de servicios&nbsp;<\/strong>que nos vincule contigo. Es posible que algunos tratamientos de datos asociados al proceso de compra se activen \u00fanicamente porque t\u00fa lo solicites o nos autorices, como es el caso del almacenamiento de los datos de pago (tarjeta) para futuras compras o del tratamiento de datos necesario para escanear los tickets de compra a trav\u00e9s de la secci\u00f3n Wallet de la App o para informarte de la disponibilidad de nuestros productos. En estos casos, la base sobre la que tratamos tus datos es tu propio&nbsp;<strong>consentimiento<\/strong>.Consideramos que tenemos un&nbsp;<strong>inter\u00e9s leg\u00edtimo&nbsp;<\/strong>para realizar las comprobaciones necesarias para detectar y prevenir posibles fraudes cuando realizas una compra. Entendemos que el tratamiento de estos datos resulta positivo para todas las partes que intervienen cuando se produce el pago de una compra y en particular para ti ya que&nbsp; nos&nbsp; permite&nbsp; poner&nbsp; medidas&nbsp; para&nbsp; protegerte&nbsp;&nbsp; contra intentos de fraude realizados por terceros.<\/td><\/tr><tr><td><strong>3. Atenci\u00f3n al Cliente<\/strong><\/td><td>Consideramos que tenemos un inter\u00e9s leg\u00edtimo para atender las solicitudes o consultas que nos plantees a trav\u00e9s de los diversos medios de contacto existentes. Entendemos que el tratamiento de estos datos resulta tambi\u00e9n beneficioso para ti en tanto que nos permite poder atenderte adecuadamente y resolver las consultas planteadas. Cuando nos contactes, en particular, para la gesti\u00f3n de incidencias relacionadas con tu pedido o el producto\/ servicio adquirido a trav\u00e9s de la web, el tratamiento es necesario para la&nbsp;<strong>ejecuci\u00f3n del contrato de compraventa<\/strong>.Cuando tu consulta est\u00e9 relacionada con el ejercicio de los derechos sobre los que te informamos m\u00e1s abajo, o con reclamaciones relacionadas con nuestros productos o servicios, lo que nos legitima para tratar tus datos es el&nbsp;<strong>cumplimiento de obligaciones legales&nbsp;<\/strong>por nuestra parte.<\/td><\/tr><tr><td><strong>4. Marketing<\/strong><\/td><td>La base leg\u00edtima para tratar tus datos con finalidades de marketing es el&nbsp;<strong>consentimiento&nbsp;<\/strong>que nos prestas, por ejemplo cuando aceptas recibir informaci\u00f3n personalizada a trav\u00e9s de diversos medios, cuando autorizas el env\u00edo de notificaciones&nbsp;<em>push&nbsp;<\/em>en tu dispositivo m\u00f3vil, o cuando aceptas las bases legales para participar en una acci\u00f3n promocional o para publicar tus fotograf\u00edas en la Plataforma o en nuestros canales de redes sociales.Para mostrarte informaci\u00f3n personalizada, consideramos que tenemos un&nbsp;<strong>inter\u00e9s leg\u00edtimo&nbsp;<\/strong>para realizar un perfilado con la informaci\u00f3n que tenemos sobre ti (como la navegaci\u00f3n que realizas, preferencias o hist\u00f3rico de compras) y los datos personales que nos has facilitado como rango de edad o idioma, ya que entendemos que el tratamiento de estos datos tambi\u00e9n resulta beneficioso para ti porque te permite mejorar tu experiencia como usuario y acceder a informaci\u00f3n de acuerdo con tus preferencias.<\/td><\/tr><tr><td><strong>5. An\u00e1lisis de usabilidad y de calidad<\/strong><\/td><td>Consideramos que tenemos un&nbsp;<strong>inter\u00e9s leg\u00edtimo&nbsp;<\/strong>para analizar la usabilidad de la web y el grado de satisfacci\u00f3n del usuario ya que entendemos que el tratamiento de estos datos tambi\u00e9n resulta beneficioso para ti porque la finalidad es mejorar la experiencia del usuario y ofrecer un servicio de mayor calidad.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>4.- \u00bfDURANTE CU\u00c1NTO TIEMPO CONSERVAREMOS TUS DATOS?<\/p>\n\n\n\n<p>El&nbsp;<strong>plazo de conservaci\u00f3n&nbsp;<\/strong>de tus datos depender\u00e1 de las finalidades para las que los tratemos, seg\u00fan lo explicado a continuaci\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>FINALIDAD<\/td><td>PLAZO DE CONSERVACION<\/td><\/tr><tr><td><strong>1. Gestionar tu registro como usuario de la WEB<\/strong><\/td><td>Trataremos tus datos durante el tiempo en que mantengas la condici\u00f3n de usuario registrado (es decir, hasta que decidas darte de baja).<\/td><\/tr><tr><td><strong>2. Desarrollo, cumplimiento y ejecuci\u00f3n del contrato de compraventa o de servicios<\/strong><\/td><td>Trataremos tus datos durante el tiempo necesario para gestionar la compra de los productos o servicios que hayas adquirido, incluyendo posibles devoluciones, quejas o reclamaciones asociadas a la compra del producto o servicio en particular.En algunas ocasiones, \u00fanicamente trataremos los datos hasta el momento en que t\u00fa decidas, como es el caso de los datos de pago (tarjeta) que nos has solicitado almacenar para posibles compras futuras.<\/td><\/tr><tr><td><strong>3. Atenci\u00f3n al Cliente<\/strong><\/td><td>Trataremos tus datos durante el tiempo que sea necesario para atender tu solicitud o petici\u00f3n.<\/td><\/tr><tr><td><strong>4. Marketing<\/strong><\/td><td>Trataremos tus datos hasta que te des de baja o canceles tu suscripci\u00f3n a la newsletter. Si participas en acciones promocionales conservaremos tus datos por un plazo de un a\u00f1o (1) a\u00f1o desde que finalice la acci\u00f3n.<\/td><\/tr><tr><td><strong>5. An\u00e1lisis de usabilidad y de calidad<\/strong><\/td><td>Trataremos tus datos puntualmente durante el tiempo en el que procedamos a realizar una acci\u00f3n o encuesta de calidad concreta o hasta que anonimicemos tus datos de navegaci\u00f3n.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong><u>IMPORTANTE<\/u><\/strong>:<\/p>\n\n\n\n<p>Independientemente de tratemos tus datos durante el tiempo estrictamente necesario para cumplir con la finalidad correspondiente, los conservaremos posteriormente debidamente guardados y protegidos durante el tiempo en que pudieran surgir responsabilidades derivadas del tratamiento, en cumplimiento con la normativa vigente en cada momento. Una vez prescriban las posibles acciones en cada caso, procederemos a la supresi\u00f3n de los datos personales.<\/p>\n\n\n\n<p>5.- \u00bfCOMPARTIREMOS TUS DATOS CON TERCEROS?<\/p>\n\n\n\n<p>Para cumplir las finalidades indicadas en la presente Pol\u00edtica de Privacidad, es necesario que demos acceso a tus datos personales a&nbsp;<strong>terceras partes&nbsp;<\/strong>que nos presten apoyo en los servicios que te ofrecemos, a saber:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Entidades&nbsp;<strong>financieras o de solvencia patrimonial.<\/strong><\/li><li>Proveedores de&nbsp;<strong>servicios tecnol\u00f3gicos<\/strong>.<\/li><li>Proveedores y colaboradores de servicios de&nbsp;<strong>log\u00edstica<\/strong>,&nbsp;<strong>transporte&nbsp;<\/strong>y&nbsp;<strong>entrega<\/strong>.<\/li><\/ul>\n\n\n\n<p>Por eficiencia del servicio, algunos de los prestadores mencionados est\u00e1n ubicados en territorios situados fuera del Espacio Econ\u00f3mico Europeo que no proporcionen un nivel de protecci\u00f3n de datos equiparable al de la Uni\u00f3n Europea, como Estados Unidos. En tales casos, te informamos de que transferimos tus datos con&nbsp;<strong>garant\u00edas adecuadas y siempre guardando la seguridad de tus datos<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Algunos proveedores est\u00e1n certificados en&nbsp;<strong>Privacy Shield<\/strong>, certificaci\u00f3n que puedes consultar en el siguiente enlace:<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.privacyshield.gov\/welcome\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>Con otros proveedores hemos firmado&nbsp;<strong>Cl\u00e1usulas Contractuales Tipo&nbsp;<\/strong>aprobadas por la Comisi\u00f3n, cuyo contenido puedes consultar en el siguiente enlace:<\/li><\/ul>\n\n\n\n<p><a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/data-transfers-outside-eu\/model-contracts-transfer-personal-data-third-countries_en\">https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/data-transfers-outside-eu\/model-contracts-<\/a>&nbsp;<a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/data-transfers-outside-eu\/model-contracts-transfer-personal-data-third-countries_en\">transfer-personal-data-third-countries_en<\/a><\/p>\n\n\n\n<p>6.- \u00bfCU\u00c1LES SON TUS DERECHOS CUANDO NOS FACILITA TUS DATOS?<\/p>\n\n\n\n<p>Nos comprometemos a respetar la confidencialidad de tus datos personales y a garantizarte el&nbsp;<strong>ejercicio de tus derechos<\/strong>. Puedes ejercitarlos&nbsp;<strong>sin coste alguno&nbsp;<\/strong>escribi\u00e9ndonos un correo electr\u00f3nico a&nbsp;<strong>nuestra direcci\u00f3n&nbsp;<\/strong><a href=\"mailto:campinghuertaromero@gmail.com\">campinghuertaromero@gmail.com<\/a>, simplemente indic\u00e1ndonos el motivo de tu solicitud y el derecho que quieres ejercitar. En caso de que lo consideremos necesario para poder identificarte, podremos solicitarte copia de un documento acreditativo de tu identidad.<\/p>\n\n\n\n<p>En particular, independientemente de la finalidad o la base legal en virtud de la que tratemos tus datos,&nbsp; en todo momento, tienes derecho a:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Acceso: Acceder a sus datos personales que disponga&nbsp;<strong>CAMPING HUERTA ROMERO.<\/strong><\/li><li>Rectificaci\u00f3n: Modificar o rectificar sus datos inexactos que disponga<strong>&nbsp;CAMPING HUERTA ROMERO.<\/strong><\/li><li>Cancelaci\u00f3n: Cancelar sus datos personales, cuando ya no sean necesarios, de la base de datos de&nbsp;<strong>CAMPING HUERTA ROMERO.<\/strong><\/li><li>Oposici\u00f3n: Oponerse a la utilizaci\u00f3n de sus datos para una finalidad que no es la elegida, de los servicios prestados por&nbsp;<strong>CAMPING HUERTA ROMERO.<\/strong><\/li><li>Portabilidad: Solicitar el cambio de expediente en un fichero automatizado para otra compa\u00f1\u00eda, desde la base de datos de&nbsp;<strong>CAMPING HUERTA ROMERO.<\/strong><\/li><li>Limitaci\u00f3n: Limitar la utilizaci\u00f3n y plazo del uso de sus datos por parte de&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>, en cuyo caso solo se conservar\u00e1n seg\u00fan la legislaci\u00f3n fiscal y para el ejercicio de reclamaciones.<\/li><li>Retirada (Derecho al Olvido): Solicitar la eliminaci\u00f3n de su historial, si procede, en Internet (V\u00e9ase RGPD).<\/li><\/ul>\n\n\n\n<p>Por \u00faltimo, te informamos de tu derecho a&nbsp;<strong>presentar una&nbsp;<\/strong>reclamaci\u00f3n ante&nbsp;<strong>la autoridad de control&nbsp;<\/strong>en materia de protecci\u00f3n de datos pertinente, en particular, ante la&nbsp;<a href=\"http:\/\/www.agpd.es\/portalwebAGPD\/index-ides-idphp.php\">Agencia Espa\u00f1ola de Protecci\u00f3n de Datos<\/a>&nbsp;(<a href=\"https:\/\/www.agpd.es\/portalwebAGPD\/index-ides-idphp.php\">https:\/\/www.agpd.es\/portalwebAGPD\/index-ides-idphp.php<\/a>)<\/p>\n\n\n\n<p>ACEPTACION Y CONSENTIMIENTO<\/p>\n\n\n\n<p>El Usuario declara haber sido informado de las condiciones sobre protecci\u00f3n de datos de car\u00e1cter personal, aceptando y consintiendo el tratamiento de los mismos por parte de&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>&nbsp;en la forma y para las finalidades indicadas en la presente Pol\u00edtica de Protecci\u00f3n de Datos Personales.<\/p>\n\n\n\n<p>7.- CAMBIOS A LA POL\u00cdTICA DE PRIVACIDAD<\/p>\n\n\n\n<p>Es posible que modifiquemos la informaci\u00f3n contenida en esta Pol\u00edtica de Privacidad cuando lo estimemos conveniente. En caso de que lo hagamos, te lo notificaremos por distintas v\u00edas a trav\u00e9s de la Plataforma (por ejemplo, a trav\u00e9s de un banner, un pop-up o una notificaci\u00f3n&nbsp;<em>push<\/em>), o incluso te lo comunicaremos a tu direcci\u00f3n de correo electr\u00f3nico cuando el cambio en cuesti\u00f3n sea significativo para con tu privacidad, de manera que puedas revisar los cambios, valorarlos y, en su caso, oponerte o darte de baja en alg\u00fan servicio o funcionalidad. En cualquier caso, te sugerimos que revises esta Pol\u00edtica de Privacidad de vez en cuando por si hubiera cambios menores o introducimos alguna mejora interactiva, aprovechando que siempre la encontrar\u00e1s como punto permanente de informaci\u00f3n en nuestra Web y nuestra App.<\/p>\n\n\n\n<p>8.- INFORMACI\u00d3N SOBRE COOKIES<\/p>\n\n\n\n<p>Utilizamos cookies y dispositivos similares para facilitar tu navegaci\u00f3n en la Plataforma, conocer c\u00f3mo interact\u00faas con Nosotros y, en determinados casos, poder mostrarte publicidad en funci\u00f3n de tus h\u00e1bitos de navegaci\u00f3n. Por favor, lee nuestra Pol\u00edtica de Cookies para conocer con mayor detalle las cookies y dispositivos similares que usamos, su finalidad y otra informaci\u00f3n de inter\u00e9s.<\/p>\n\n\n\n<p><strong>3.- POLITICA DE COOKIES<\/strong><\/p>\n\n\n\n<p><strong>POL\u00cdTICA DE COOKIES.<\/strong><\/p>\n\n\n\n<p><strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>a trav\u00e9s del presente documento, recoge su Pol\u00edtica de recogida y tratamiento de cookies, en cumplimiento de lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSICE).<\/p>\n\n\n\n<p>Las cookies se almacenan en el equipo terminal del usuario (ordenador o dispositivo m\u00f3vil) y recopilan informaci\u00f3n al visitar la p\u00e1gina web&nbsp;<a href=\"https:\/\/www.campinghuertaromero.es\/\">www.campinghuertaromero.es<\/a>&nbsp;con la finalidad de mejorar la usabilidad de las mismas, conocer los h\u00e1bitos o necesidades de navegaci\u00f3n de los usuarios para poder adaptarse a los mismos, as\u00ed como obtener informaci\u00f3n con fines estad\u00edsticos. En el caso de aquellos usuarios que ya sean clientes de&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>, la informaci\u00f3n recabada con las cookies servir\u00e1 tambi\u00e9n para su identificaci\u00f3n al acceder a las distintas herramientas que&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>pone a su disposici\u00f3n para la gesti\u00f3n de los servicios.<\/p>\n\n\n\n<p>La presente Pol\u00edtica de Cookies ser\u00e1 de aplicaci\u00f3n a aquellos usuarios que voluntariamente visitan las p\u00e1ginas web de&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>, cumplimentan formularios de recogida de datos, acceden a las herramientas que&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>pone a disposici\u00f3n de sus clientes para gestionar sus servicios, o utilizan cualquier otro servicio presente en el sitio web que implique la comunicaci\u00f3n de datos a&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>, o el acceso a datos para la prestaci\u00f3n de sus servicios.<\/p>\n\n\n\n<p><strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>informa a los usuarios de sus p\u00e1ginas web, de la existencia de cookies y pone a su disposici\u00f3n la presente Pol\u00edtica con la finalidad de informarles acerca del uso y del objeto de las mismas. El hecho de continuar la navegaci\u00f3n a trav\u00e9s de sus p\u00e1ginas, supone el conocimiento y la aceptaci\u00f3n de la presente Pol\u00edtica por parte de dichos usuarios.<\/p>\n\n\n\n<p><strong>CAMPING HUERTA ROMERO&nbsp;<\/strong><strong>utiliza los siguientes tipos de cookies:<\/strong><\/p>\n\n\n\n<p>Clasificadas por su titularidad:<\/p>\n\n\n\n<p>* Cookies propias: enviadas y gestionadas directamente por&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>.&nbsp;<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>* Cookies de terceros: enviadas y gestionadas por un tercero ajeno a&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>de forma an\u00f3nima, con la finalidad de realizar estudios estad\u00edsticos de navegaci\u00f3n por las p\u00e1ginas web de&nbsp;<strong>CAMPING HUERTA ROMERO<\/strong>. &nbsp;<strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>Clasificadas por su finalidad:<\/p>\n\n\n\n<p>* Cookies t\u00e9cnicas y\/o de personalizaci\u00f3n: facilitan la navegaci\u00f3n, al identificar la sesi\u00f3n, permitir el acceso a herramientas de acceso restringido, adem\u00e1s de configurar a medida las opciones disponibles. Posibilitan la prestaci\u00f3n del servicio solicitado previamente por el usuario.<\/p>\n\n\n\n<p>* Cookies de an\u00e1lisis y\/o publicidad: permiten conocer el n\u00famero de visitas recibidas en las diferentes secciones de las p\u00e1ginas web, los h\u00e1bitos y tendencias de sus usuarios y en consecuencia, poder mejorar la navegaci\u00f3n y el servicio ofrecido por&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>fundamentalmente, Google Analytics), as\u00ed como gestionar los espacios publicitarios incluidos en la p\u00e1gina web visitada por el usuario. Recopila datos de forma an\u00f3nima con la finalidad de obtener perfiles de navegaci\u00f3n de los usuarios.<\/p>\n\n\n\n<p>Clasificadas por su duraci\u00f3n:<\/p>\n\n\n\n<p>* Cookies de sesi\u00f3n: recaban y almacenan los datos mientras el usuario accede a la p\u00e1gina web.<\/p>\n\n\n\n<p>* Cookies persistentes: recaban y almacenan los datos en el terminal del usuario durante un periodo de tiempo variable en funci\u00f3n de cu\u00e1l sea la finalidad para la que han sido utilizadas.<\/p>\n\n\n\n<p>El tiempo de conservaci\u00f3n de las cookies depender\u00e1 del tipo de que se trate y siempre ser\u00e1 el m\u00ednimo indispensable para cumplir su finalidad.<\/p>\n\n\n\n<p>En cualquier caso, los usuarios pueden configurar su navegador, de manera que se deshabilite o bloquee la recepci\u00f3n de todas o algunas de las cookies. El hecho de no desear recibir estas cookies, no constituye un impedimento para poder acceder a la informaci\u00f3n de los sitios web de&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>aunque el uso de algunos servicios podr\u00e1 ser limitado. Si una vez otorgado el consentimiento para la recepci\u00f3n de cookies, se desease retirar \u00e9ste, se deber\u00e1n eliminar aquellas almacenadas en el equipo del usuario, a trav\u00e9s de las opciones de los diferentes navegadores.<\/p>\n\n\n\n<p>La forma de configurar los diferentes navegadores para ejercitar las acciones se\u00f1aladas en los p\u00e1rrafos anteriores, se puede consultar en:<\/p>\n\n\n\n<p>*Explorer:http:\/\/windows.microsoft.com\/es-es\/windows7\/how-to-manage-cookies-in-internet-explorer-9<\/p>\n\n\n\n<p>* Chrome: https:\/\/support.google.com\/chrome\/answer\/95647?hl=es<\/p>\n\n\n\n<p>* Firefox: http:\/\/support.mozilla.org\/es\/kb\/cookies-informacion-que-los-sitios-web-guardan-en-?redirectlocale=en-US&amp;redirectslug=Cookies<\/p>\n\n\n\n<p><strong>BASES DE CONCURSOS<\/strong><\/p>\n\n\n\n<p><strong>Bases legales de participaci\u00f3n en la Promoci\u00f3n<\/strong><\/p>\n\n\n\n<p><strong>1.- EMPRESA ORGANIZADORA DE LA PROMOCI\u00d3N<\/strong><\/p>\n\n\n\n<p>MIGUEL GONZ\u00c1LEZ MICHAELIS, en adelante,&nbsp;<strong>CAMPING HUERTA ROMERO,<\/strong>&nbsp;con domicilio en PASEO MARITIMO, 18, 18740, CASTELL DE FERRO, GRANADA y NIF n\u00ba 51095018-N, organiza con fines promocionales el [sorteo\/concurso] (en adelante, \u201cla Promoci\u00f3n\u201d) de \u00e1mbito local, a desarrollar a trav\u00e9s de Internet, exclusivo para usuarios residentes en [__________] y mayores de edad de acuerdo con lo dispuesto en el apartado de condiciones para participar.<\/p>\n\n\n\n<p><strong>2.-FECHA DE INICIO Y FECHA DE FINALIZACI\u00d3N<\/strong><\/p>\n\n\n\n<p>La Promoci\u00f3n&nbsp; se iniciar\u00e1 el d\u00eda[__________], y finalizar\u00e1 el d\u00eda [_________].<\/p>\n\n\n\n<p><strong>3.- REQUISITOS DE PARTICIPACI\u00d3N Y MEC\u00c1NICA DE LA PROMOCI\u00d3N<\/strong><\/p>\n\n\n\n<p>Los requisitos de participaci\u00f3n ser\u00e1n los siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Podr\u00e1n participar aquellas personas que residan en [__________]y sean mayores de [__________].<\/li><li>S\u00f3lo podr\u00e1n participar aquellos participantes que [_____________].<\/li><li>Los datos personales con los que los participantes rellenen el formulario de inscripci\u00f3n deber\u00e1n ser datos veraces.<\/li><li>Los Participantes s\u00f3lo podr\u00e1n inscribirse una vez en la presente promoci\u00f3n.<\/li><\/ul>\n\n\n\n<p>La mec\u00e1nica de la Promoci\u00f3n consiste en[___________________].<\/p>\n\n\n\n<p><strong>4.- CONDICIONES DE LA PROMOCI\u00d3NY PREMIOS<\/strong><\/p>\n\n\n\n<p>Se elegir\u00e1 [______] ganador\/es y [______] suplente\/s [de manera aleatoria\/en base al criterio del jurado interno] el d\u00eda [________________].<\/p>\n\n\n\n<p>El\/Los ganador\/es obtendr\u00e1\/n como premio: [____________].<\/p>\n\n\n\n<p><strong>5.- DESCALIFICACIONES Y PENALIZACIONES<\/strong><\/p>\n\n\n\n<p>Si se evidenciase que cualquiera de los participantes no cumple con los requisitos exigidos en las Bases, o los datos proporcionados para participar no fueran v\u00e1lidos, su participaci\u00f3n se considerar\u00e1 nula y quedar\u00e1n autom\u00e1ticamente excluidos de la Promoci\u00f3n perdiendo todo derecho sobre los premios otorgados en virtud de esta Promoci\u00f3n.<\/p>\n\n\n\n<p><strong>6.- PUBLICACI\u00d3N DE COMENTARIOS U OPINIONES<\/strong><\/p>\n\n\n\n<p>No se permitir\u00e1n comentarios u opiniones cuyo contenido se considere inadecuado, que sean ofensivos, injuriosos o discriminatorios o que pudieran vulnerar derechos de terceros. Tampoco ser permitir\u00e1 comentarios contra un particular que vulneren los principios de derecho al honor, a la intimidad personal y familiar y a la propia imagen. No nos responsabilizaremos de los da\u00f1os ocasionados por los comentarios que hagan los participantes en la Promoci\u00f3n, y que en cualquier momento pudieran herir la sensibilidad de otros participantes.<\/p>\n\n\n\n<p><strong>7.<\/strong><strong>-EXONERACI\u00d3N DE RESPONSABILIDAD<\/strong><\/p>\n\n\n\n<p>A t\u00edtulo enunciativo, pero no limitativo, no nos responsabilizamos de las posibles p\u00e9rdidas, robos, retrasos o cualquiera otra circunstancia imputable a terceros que puedan afectar al desarrollo de la presente Promoci\u00f3n, as\u00ed como tampoco nos responsabilizamos a del uso que haga el participante respecto del premio que obtenga de esta Promoci\u00f3n.<\/p>\n\n\n\n<p>No asumimos la responsabilidad en casos de fuerza mayor o caso fortuito que pudieran impedir la realizaci\u00f3n de la Promoci\u00f3n o el disfrute total o parcial del premio.<\/p>\n\n\n\n<p><strong>8.- FACEBOOK (en caso de promoci\u00f3n en Facebook)<\/strong><\/p>\n\n\n\n<p>La promoci\u00f3n no est\u00e1 patrocinada, avalada, administrada ni asociada en modo alguno a Facebook por lo que los participantes liberan a Facebook de toda responsabilidad por los eventuales da\u00f1os que se deriven de la misma.<\/p>\n\n\n\n<p><strong>9.- PROTECCI\u00d3N DE DATOS PERSONALES<\/strong><\/p>\n\n\n\n<p>De conformidad con lo establecido en la Ley Org\u00e1nica 15\/1999, de 11 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal, y en su Reglamento de desarrollo, cada participante con la aceptaci\u00f3n de estas bases legales consiente que sus datos personales ser\u00e1n incorporados a un fichero, de cual es responsable&nbsp;<strong>CAMPING HUERTA ROMERO&nbsp;<\/strong>y utilizados para remitirle Newsletters y comunicaciones comerciales y promocionales relacionadas con nuestros servicios por carta, tel\u00e9fono, correo electr\u00f3nico, SMS\/MMS, o por otros medios de comunicaci\u00f3n electr\u00f3nica, as\u00ed como para la publicaci\u00f3n de los resultados de dicha promoci\u00f3n en los medios habituales de difusi\u00f3n que utiliza nuestra empresa.<\/p>\n\n\n\n<p>Le informamos que puede ejercer sus derechos de Acceso, Rectificaci\u00f3n, Cancelaci\u00f3n y Oposici\u00f3n, as\u00ed como el de Portabilidad y Limitaci\u00f3n y retirada, utilizando los formularios que disponemos para ello, o bien mediante el env\u00edo de un e-mail a&nbsp;<a href=\"mailto:campinghuertaromero@gmail.com\">campinghuertaromero@gmail.com<\/a>&nbsp;o bien mediante carta dirigida a la siguiente direcci\u00f3n: PASEO MARITIMO, 18, 18740, CASTELL DE FERRO, GRANADA, adjuntando en ambos casos copia del DNI.<\/p>\n\n\n\n<p><strong>10.- CAMBIOS<\/strong><\/p>\n\n\n\n<p>Nos reservamos el derecho de modificar o ampliar estas bases promocionales, en la medida que no perjudique o menoscabe los derechos de los participantes en la Promoci\u00f3n.<\/p>\n\n\n\n<p><strong>11.- LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/strong><\/p>\n\n\n\n<p>Estas bases legales se regir\u00e1n de conformidad con la ley espa\u00f1ola. Ser\u00e1n competentes para resolver cualquier reclamaci\u00f3n o controversia que pudiera plantearse en relaci\u00f3n con la validez, interpretaci\u00f3n o cumplimiento de estas bases los Juzgados y Tribunales de Murcia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1.- AVISO LEGAL 2.- POLITICA DE PRIVACIDAD 3.- POLITICA DE COOKIES 4.- FALDON COOKIES 5.- BASES ESTANDAR CONCURSOS 6.- TEXTO AUTORIZACION CONTACTO 7.- FORMATO AUTORIZACION NEWSLETTER AVISO LEGAL&nbsp; AVISO LEGAL: &nbsp;En cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSICE) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1428","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/pages\/1428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/comments?post=1428"}],"version-history":[{"count":1,"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/pages\/1428\/revisions"}],"predecessor-version":[{"id":1429,"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/pages\/1428\/revisions\/1429"}],"wp:attachment":[{"href":"https:\/\/campinghuertaromero.es\/en\/wp-json\/wp\/v2\/media?parent=1428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}